{"id":95034,"date":"2022-10-21T16:10:52","date_gmt":"2022-10-21T16:10:52","guid":{"rendered":"https:\/\/www.gcx.com\/solutions\/medical-devices\/channel-mounts\/"},"modified":"2024-03-29T19:19:29","modified_gmt":"2024-03-29T19:19:29","slug":"channel-mounts","status":"publish","type":"gcx_manufacturers","link":"https:\/\/www.gcx.com\/es\/solutions\/medical-devices\/philips\/intellivue\/mx600-mx700-mx800\/dual-fmx-4\/channel-mounts\/","title":{"rendered":"Channel Mounts"},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":31709,"parent":95033,"menu_order":0,"template":"","class_list":["post-95034","gcx_manufacturers","type-gcx_manufacturers","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Channel Mounts | Soluciones de montaje GCX Medical<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.gcx.com\/es\/solutions\/medical-devices\/philips\/intellivue\/mx600-mx700-mx800\/dual-fmx-4\/channel-mounts\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Channel Mounts | Soluciones de montaje GCX Medical\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.gcx.com\/es\/solutions\/medical-devices\/philips\/intellivue\/mx600-mx700-mx800\/dual-fmx-4\/channel-mounts\/\" \/>\n<meta property=\"og:site_name\" content=\"Soluciones de montaje GCX Medical\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GCXMountingSolutions\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-29T19:19:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.gcx.com\/wp-content\/uploads\/2024\/02\/Philips_MX850_With_Dual_FMX-4_on_VHM-PL_L_2022-10-21-160629_rwwa-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@gcxcorp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gcx.com\\\/es\\\/solutions\\\/medical-devices\\\/philips\\\/intellivue\\\/mx600-mx700-mx800\\\/dual-fmx-4\\\/channel-mounts\\\/\",\"url\":\"https:\\\/\\\/www.gcx.com\\\/es\\\/solutions\\\/medical-devices\\\/philips\\\/intellivue\\\/mx600-mx700-mx800\\\/dual-fmx-4\\\/channel-mounts\\\/\",\"name\":\"Channel Mounts | Soluciones de montaje GCX Medical\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gcx.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.gcx.com\\\/es\\\/solutions\\\/medical-devices\\\/philips\\\/intellivue\\\/mx600-mx700-mx800\\\/dual-fmx-4\\\/channel-mounts\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gcx.com\\\/es\\\/solutions\\\/medical-devices\\\/philips\\\/intellivue\\\/mx600-mx700-mx800\\\/dual-fmx-4\\\/channel-mounts\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.gcx.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Philips_MX850_With_Dual_FMX-4_on_VHM-PL_L_2022-10-21-160629_rwwa-scaled.jpg\",\"datePublished\":\"2022-10-21T16:10:52+00:00\",\"dateModified\":\"2024-03-29T19:19:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gcx.com\\\/es\\\/solutions\\\/medical-devices\\\/philips\\\/intellivue\\\/mx600-mx700-mx800\\\/dual-fmx-4\\\/channel-mounts\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.gcx.com\\\/es\\\/solutions\\\/medical-devices\\\/philips\\\/intellivue\\\/mx600-mx700-mx800\\\/dual-fmx-4\\\/channel-mounts\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.gcx.com\\\/es\\\/solutions\\\/medical-devices\\\/philips\\\/intellivue\\\/mx600-mx700-mx800\\\/dual-fmx-4\\\/channel-mounts\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.gcx.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Philips_MX850_With_Dual_FMX-4_on_VHM-PL_L_2022-10-21-160629_rwwa-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.gcx.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Philips_MX850_With_Dual_FMX-4_on_VHM-PL_L_2022-10-21-160629_rwwa-scaled.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"Philips MX850 With Dual FMX 4 on VHM PL L\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gcx.com\\\/es\\\/solutions\\\/medical-devices\\\/philips\\\/intellivue\\\/mx600-mx700-mx800\\\/dual-fmx-4\\\/channel-mounts\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.gcx.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Philips\",\"item\":\"https:\\\/\\\/www.gcx.com\\\/es\\\/solutions\\\/medical-devices\\\/philips\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"IntelliVue\",\"item\":\"https:\\\/\\\/www.gcx.com\\\/es\\\/solutions\\\/medical-devices\\\/philips\\\/intellivue\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"MX600\\\/700\\\/800\",\"item\":\"https:\\\/\\\/www.gcx.com\\\/es\\\/solutions\\\/medical-devices\\\/philips\\\/intellivue\\\/mx600-mx700-mx800\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Dual FMX-4\",\"item\":\"https:\\\/\\\/www.gcx.com\\\/es\\\/solutions\\\/medical-devices\\\/philips\\\/intellivue\\\/mx600-mx700-mx800-mx850\\\/dual-fmx-4\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"Channel Mounts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gcx.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.gcx.com\\\/es\\\/\",\"name\":\"GCX Medical Mounting Solutions\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.gcx.com\\\/es\\\/#organization\"},\"alternateName\":\"GCX\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.gcx.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.gcx.com\\\/es\\\/#organization\",\"name\":\"GCX Medical Mounting Solutions\",\"alternateName\":\"GCX\",\"url\":\"https:\\\/\\\/www.gcx.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.gcx.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.gcx.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/gcx_logo.png\",\"contentUrl\":\"https:\\\/\\\/www.gcx.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/gcx_logo.png\",\"width\":400,\"height\":166,\"caption\":\"GCX Medical Mounting Solutions\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gcx.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GCXMountingSolutions\\\/\",\"https:\\\/\\\/x.com\\\/gcxcorp\",\"https:\\\/\\\/linkedin.com\\\/company\\\/gcx\",\"https:\\\/\\\/www.instagram.com\\\/gcxcorp\",\"https:\\\/\\\/www.youtube.com\\\/gcxcorp\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Channel Mounts | Soluciones de montaje GCX Medical","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.gcx.com\/es\/solutions\/medical-devices\/philips\/intellivue\/mx600-mx700-mx800\/dual-fmx-4\/channel-mounts\/","og_locale":"es_ES","og_type":"article","og_title":"Channel Mounts | Soluciones de montaje GCX Medical","og_url":"https:\/\/www.gcx.com\/es\/solutions\/medical-devices\/philips\/intellivue\/mx600-mx700-mx800\/dual-fmx-4\/channel-mounts\/","og_site_name":"Soluciones de montaje GCX Medical","article_publisher":"https:\/\/www.facebook.com\/GCXMountingSolutions\/","article_modified_time":"2024-03-29T19:19:29+00:00","og_image":[{"width":2560,"height":2560,"url":"https:\/\/www.gcx.com\/wp-content\/uploads\/2024\/02\/Philips_MX850_With_Dual_FMX-4_on_VHM-PL_L_2022-10-21-160629_rwwa-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@gcxcorp","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.gcx.com\/es\/solutions\/medical-devices\/philips\/intellivue\/mx600-mx700-mx800\/dual-fmx-4\/channel-mounts\/","url":"https:\/\/www.gcx.com\/es\/solutions\/medical-devices\/philips\/intellivue\/mx600-mx700-mx800\/dual-fmx-4\/channel-mounts\/","name":"Channel Mounts | Soluciones de montaje GCX Medical","isPartOf":{"@id":"https:\/\/www.gcx.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.gcx.com\/es\/solutions\/medical-devices\/philips\/intellivue\/mx600-mx700-mx800\/dual-fmx-4\/channel-mounts\/#primaryimage"},"image":{"@id":"https:\/\/www.gcx.com\/es\/solutions\/medical-devices\/philips\/intellivue\/mx600-mx700-mx800\/dual-fmx-4\/channel-mounts\/#primaryimage"},"thumbnailUrl":"https:\/\/www.gcx.com\/wp-content\/uploads\/2024\/02\/Philips_MX850_With_Dual_FMX-4_on_VHM-PL_L_2022-10-21-160629_rwwa-scaled.jpg","datePublished":"2022-10-21T16:10:52+00:00","dateModified":"2024-03-29T19:19:29+00:00","breadcrumb":{"@id":"https:\/\/www.gcx.com\/es\/solutions\/medical-devices\/philips\/intellivue\/mx600-mx700-mx800\/dual-fmx-4\/channel-mounts\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.gcx.com\/es\/solutions\/medical-devices\/philips\/intellivue\/mx600-mx700-mx800\/dual-fmx-4\/channel-mounts\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.gcx.com\/es\/solutions\/medical-devices\/philips\/intellivue\/mx600-mx700-mx800\/dual-fmx-4\/channel-mounts\/#primaryimage","url":"https:\/\/www.gcx.com\/wp-content\/uploads\/2024\/02\/Philips_MX850_With_Dual_FMX-4_on_VHM-PL_L_2022-10-21-160629_rwwa-scaled.jpg","contentUrl":"https:\/\/www.gcx.com\/wp-content\/uploads\/2024\/02\/Philips_MX850_With_Dual_FMX-4_on_VHM-PL_L_2022-10-21-160629_rwwa-scaled.jpg","width":2560,"height":2560,"caption":"Philips MX850 With Dual FMX 4 on VHM PL L"},{"@type":"BreadcrumbList","@id":"https:\/\/www.gcx.com\/es\/solutions\/medical-devices\/philips\/intellivue\/mx600-mx700-mx800\/dual-fmx-4\/channel-mounts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.gcx.com\/es\/"},{"@type":"ListItem","position":2,"name":"Philips","item":"https:\/\/www.gcx.com\/es\/solutions\/medical-devices\/philips\/"},{"@type":"ListItem","position":3,"name":"IntelliVue","item":"https:\/\/www.gcx.com\/es\/solutions\/medical-devices\/philips\/intellivue\/"},{"@type":"ListItem","position":4,"name":"MX600\/700\/800","item":"https:\/\/www.gcx.com\/es\/solutions\/medical-devices\/philips\/intellivue\/mx600-mx700-mx800\/"},{"@type":"ListItem","position":5,"name":"Dual FMX-4","item":"https:\/\/www.gcx.com\/es\/solutions\/medical-devices\/philips\/intellivue\/mx600-mx700-mx800-mx850\/dual-fmx-4\/"},{"@type":"ListItem","position":6,"name":"Channel Mounts"}]},{"@type":"WebSite","@id":"https:\/\/www.gcx.com\/es\/#website","url":"https:\/\/www.gcx.com\/es\/","name":"GCX Medical Mounting Solutions","description":"","publisher":{"@id":"https:\/\/www.gcx.com\/es\/#organization"},"alternateName":"GCX","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.gcx.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.gcx.com\/es\/#organization","name":"GCX Medical Mounting Solutions","alternateName":"GCX","url":"https:\/\/www.gcx.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.gcx.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.gcx.com\/wp-content\/uploads\/2024\/02\/gcx_logo.png","contentUrl":"https:\/\/www.gcx.com\/wp-content\/uploads\/2024\/02\/gcx_logo.png","width":400,"height":166,"caption":"GCX Medical Mounting Solutions"},"image":{"@id":"https:\/\/www.gcx.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GCXMountingSolutions\/","https:\/\/x.com\/gcxcorp","https:\/\/linkedin.com\/company\/gcx","https:\/\/www.instagram.com\/gcxcorp","https:\/\/www.youtube.com\/gcxcorp"]}]}},"_links":{"self":[{"href":"https:\/\/www.gcx.com\/es\/wp-json\/wp\/v2\/gcx_manufacturers\/95034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gcx.com\/es\/wp-json\/wp\/v2\/gcx_manufacturers"}],"about":[{"href":"https:\/\/www.gcx.com\/es\/wp-json\/wp\/v2\/types\/gcx_manufacturers"}],"author":[{"embeddable":true,"href":"https:\/\/www.gcx.com\/es\/wp-json\/wp\/v2\/users\/1"}],"up":[{"embeddable":true,"href":"https:\/\/www.gcx.com\/es\/wp-json\/wp\/v2\/gcx_manufacturers\/95033"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gcx.com\/es\/wp-json\/wp\/v2\/media\/31709"}],"wp:attachment":[{"href":"https:\/\/www.gcx.com\/es\/wp-json\/wp\/v2\/media?parent=95034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}